{"id":8159,"date":"2025-09-28T16:11:45","date_gmt":"2025-09-28T16:11:45","guid":{"rendered":"https:\/\/www.orioncenter.be\/?page_id=8159"},"modified":"2025-10-18T20:17:04","modified_gmt":"2025-10-18T20:17:04","slug":"boogschieten","status":"publish","type":"page","link":"https:\/\/www.orioncenter.be\/fr_be\/boogschieten\/","title":{"rendered":"tir \u00e0 l'arc"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"8159\" class=\"elementor elementor-8159\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4443d08d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle jltma-glass-effect-no\" data-id=\"4443d08d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ba6da47 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"1ba6da47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f1dcbab elementor-icon-list--layout-inline elementor-tablet-align-center elementor-align-center elementor-mobile-align-center elementor-list-item-link-full_width jltma-glass-effect-no elementor-widget elementor-widget-icon-list\" data-id=\"5f1dcbab\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">tir \u00e0 l'arc<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb2630a elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-reverse-tablet elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"bb2630a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-12249ae sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"12249ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76adc9b jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"76adc9b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg\" class=\"attachment-large size-large wp-image-8199\" alt=\"asian girl shooting bow and arrow indoor\" srcset=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg 1024w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-300x226.jpg 300w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-768x578.jpg 768w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1536x1155.jpg 1536w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-16x12.jpg 16w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-370x278.jpg 370w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-760x572.jpg 760w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed.jpg 1996w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f747632 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"f747632\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-212ccef jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"212ccef\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a8fe77 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3a8fe77\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">tir \u00e0 l'arc<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1436bfb jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"1436bfb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0<\/p><p class=\"whitespace-normal break-words\">Le tir \u00e0 l'arc ne doit pas s'arr\u00eater lorsque le temps belge s'installe !<\/p><p class=\"whitespace-normal break-words\">Dans notre centre multisports de Weelde, nous proposons d'excellentes installations de tir \u00e0 l'arc en salle sur notre stand professionnel de 30 m\u00e8tres.<\/p><p class=\"whitespace-normal break-words\">Que vous soyez un d\u00e9butant souhaitant s'initier au tir \u00e0 l'arc ou un archer exp\u00e9riment\u00e9, jeune ou moins jeune, nos installations int\u00e9rieures permettent de s'entra\u00eener et de participer \u00e0 des comp\u00e9titions tout au long de l'ann\u00e9e.<\/p><p>Les athl\u00e8tes Handisport peuvent facilement acc\u00e9der \u00e0 la tribune gr\u00e2ce \u00e0 notre ascenseur.<\/p><h3 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\"><strong>Pourquoi le tir \u00e0 l'arc en salle \u00e0 Weelde ?<\/strong><\/h3><p class=\"whitespace-normal break-words\">Notre stand de tir \u00e0 l'arc en salle de 8 m\u00e8tres de large et de 30 m\u00e8tres de long offre des conditions optimales pour diff\u00e9rentes disciplines et concepts de comp\u00e9tition. En tant que club de tir \u00e0 l'arc dans la r\u00e9gion au nord d'Anvers, nous organisons r\u00e9guli\u00e8rement des comp\u00e9titions et des s\u00e9ances de tir pour tous les niveaux.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79302f12 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"79302f12\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15e3a110 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"15e3a110\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a863eb1 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4a863eb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">18 m\u00e8tres <\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7daacbf4 jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"7daacbf4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\"><strong>Disciplines de comp\u00e9tition en salle : Du d\u00e9butant au professionnel<\/strong><\/h3><p class=\"whitespace-normal break-words\"><strong>\u00a0Matches de 18 m\u00e8tres (approuv\u00e9s par le BAIC)<\/strong> Pour les tireurs \u00e0 la recherche d'une comp\u00e9tition s\u00e9rieuse : matchs officiels reconnus par la WA o\u00f9 vous tirez 2 s\u00e9ries de 30 fl\u00e8ches \u00e0 18 m\u00e8tres. Le tour de qualification est suivi de matchs individuels passionnants jusqu'\u00e0 ce que le vainqueur soit connu. Une pr\u00e9paration parfaite pour les s\u00e9lections internationales.<\/p><p class=\"whitespace-normal break-words\"><strong>Comp\u00e9titions Interclub de 18 m\u00e8tres<\/strong> Id\u00e9al pour apprendre le tir \u00e0 l'arc dans une atmosph\u00e8re d\u00e9tendue ! Tirez vos 60 fl\u00e8ches quand vous le souhaitez : vendredi, samedi ou dimanche. Pas de pression, mais l'excitation d'une vraie comp\u00e9tition.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c43c88c sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"1c43c88c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ad756ed jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"4ad756ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"681\" data-src=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-1024x681.jpg\" class=\"attachment-large size-large wp-image-8221 lazyload\" alt=\"multiple archery targets\" data-srcset=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-1024x681.jpg 1024w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-300x199.jpg 300w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-768x511.jpg 768w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-1536x1021.jpg 1536w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-2048x1361.jpg 2048w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-18x12.jpg 18w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-370x246.jpg 370w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-568x379.jpg 568w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_81958-payed-15-09-25-compressed-760x505.jpg 760w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/681;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-204ec780 elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"204ec780\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eed04ae sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"eed04ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-317140ff jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"317140ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" data-src=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-1024x682.jpg\" class=\"attachment-large size-large wp-image-8220 lazyload\" alt=\"box of arrow shafts and target\" data-srcset=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-1024x682.jpg 1024w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-300x200.jpg 300w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-768x511.jpg 768w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-1536x1023.jpg 1536w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-2048x1364.jpg 2048w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-18x12.jpg 18w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-370x246.jpg 370w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-124x84.jpg 124w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-568x379.jpg 568w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_74619220-payed-15-09-25-compressed-760x506.jpg 760w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/682;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a02add9 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"a02add9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22a97c6b jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"22a97c6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">25 M\u00e8tres <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f427288 jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"3f427288\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0<\/p><p class=\"whitespace-normal break-words\"><strong>25 M\u00e8tres Disciplines<\/strong> Les tireurs exp\u00e9riment\u00e9s peuvent choisir entre :<\/p><p><strong>25M3P<\/strong>: 2 s\u00e9ries de 30 fl\u00e8ches (60 fl\u00e8ches au total)<\/p><p><strong>25M1P<\/strong>1 s\u00e9rie de 30 fl\u00e8ches - parfaite pour une s\u00e9ance courte mais intense<\/p><p>Pour plus d'informations sur les diff\u00e9rentes disciplines de l'arc, veuillez contacter <a href=\"https:\/\/www.boogsport.vlaanderen\/\">Boogsport Vlaanderen<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7b16efcc elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"7b16efcc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cc8f987 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"5cc8f987\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e573af6 jltma-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4e573af6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fun Shoot<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64952407 jltma-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"64952407\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"text-lg font-bold text-text-100 mt-1 -mb-1.5\"><strong>Plus que des comp\u00e9titions<\/strong><\/h3><p class=\"whitespace-normal break-words\">Outre les comp\u00e9titions, nous avons l'intention d'organiser des fun shoots et des \u00e9v\u00e9nements sp\u00e9ciaux \u00e0 Weelde. Nos installations indoor rendent tout cela possible, quel que soit le temps qu'il fait \u00e0 l'ext\u00e9rieur.<\/p><p>Si vous \u00eates \u00e0 la recherche d'un lieu unique pour un \u00e9v\u00e9nement professionnel ou une f\u00eate d'anniversaire amusante, vous avez frapp\u00e9 \u00e0 la bonne porte au Centre de formation Orion.<\/p><p class=\"whitespace-normal break-words\"><strong>Pr\u00eat \u00e0 faire du tir \u00e0 l'arc \u00e0 Weelde ?<\/strong><\/p><p class=\"whitespace-normal break-words\">Contactez-nous bient\u00f4t pour plus d'informations sur les possibilit\u00e9s d'entra\u00eenement, les comp\u00e9titions et les tirs de plaisir dans notre centre multisports ultramoderne !<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e3be63a sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"2e3be63a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ecf09b9 jltma-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"1ecf09b9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-1024x683.jpg\" class=\"attachment-large size-large wp-image-8216 lazyload\" alt=\"man met das en boog die arm opheft omwille van overwinning\" data-srcset=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-1024x683.jpg 1024w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-300x200.jpg 300w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-768x512.jpg 768w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-1536x1024.jpg 1536w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-2048x1365.jpg 2048w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-18x12.jpg 18w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-370x247.jpg 370w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-124x84.jpg 124w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-568x379.jpg 568w, https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_19244504-payed-15-09-25-compressed-760x507.jpg 760w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1031664 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"1031664\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-331ba19 sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"331ba19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b5e91b sc_height_tiny jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"4b5e91b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d90346 elementor-section-boxed elementor-section-height-default elementor-section-height-default jltma-glass-effect-no\" data-id=\"8d90346\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7aec9a sc_layouts_column_icons_position_left jltma-glass-effect-no\" data-id=\"e7aec9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b4819e jltma-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"3b4819e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Boogschieten Boogschieten \u00a0 Boogschieten hoeft niet te stoppen wanneer het Belgisch weer toeslaat! In ons Multi sportcentrum te Weelde bieden we uitstekende indoor&hellip;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":445,"footnotes":""},"class_list":["post-8159","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boogschieten: Het hele jaar door plezier<\/title>\n<meta name=\"description\" content=\"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.orioncenter.be\/fr_be\/boogschieten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boogschieten\" \/>\n<meta property=\"og:description\" content=\"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.orioncenter.be\/fr_be\/boogschieten\/\" \/>\n<meta property=\"og:site_name\" content=\"Orion Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61567727466888\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-18T20:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1996\" \/>\n\t<meta property=\"og:image:height\" content=\"1501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/\",\"url\":\"https:\/\/www.orioncenter.be\/boogschieten\/\",\"name\":\"Boogschieten: Het hele jaar door plezier\",\"isPartOf\":{\"@id\":\"https:\/\/www.orioncenter.be\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg\",\"datePublished\":\"2025-09-28T16:11:45+00:00\",\"dateModified\":\"2025-10-18T20:17:04+00:00\",\"description\":\"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.orioncenter.be\/boogschieten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage\",\"url\":\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg\",\"contentUrl\":\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.orioncenter.be\/boogschieten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.orioncenter.be\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boogschieten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.orioncenter.be\/#website\",\"url\":\"https:\/\/www.orioncenter.be\/\",\"name\":\"Orioncenter.be\",\"description\":\"Belgium's premier shooting range\",\"publisher\":{\"@id\":\"https:\/\/www.orioncenter.be\/#organization\"},\"alternateName\":\"Orion Training Center\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.orioncenter.be\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.orioncenter.be\/#organization\",\"name\":\"Orion Training Center\",\"alternateName\":\"Orion Training Center\",\"url\":\"https:\/\/www.orioncenter.be\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.orioncenter.be\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2024\/11\/Logo-website-2024-transparant-metal.png\",\"contentUrl\":\"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2024\/11\/Logo-website-2024-transparant-metal.png\",\"width\":1875,\"height\":625,\"caption\":\"Orion Training Center\"},\"image\":{\"@id\":\"https:\/\/www.orioncenter.be\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=61567727466888\",\"https:\/\/www.youtube.com\/channel\/UCSOma6ruzcdrtKz72WYeTVQ\",\"https:\/\/www.instagram.com\/oriontrainingcenter_belgium?igsh=OTdwdHc5M2tuNTl4&utm_source=qr\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boogschieten: Het hele jaar door plezier","description":"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.orioncenter.be\/fr_be\/boogschieten\/","og_locale":"fr_FR","og_type":"article","og_title":"Boogschieten","og_description":"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.","og_url":"https:\/\/www.orioncenter.be\/fr_be\/boogschieten\/","og_site_name":"Orion Center","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61567727466888","article_modified_time":"2025-10-18T20:17:04+00:00","og_image":[{"width":1996,"height":1501,"url":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.orioncenter.be\/boogschieten\/","url":"https:\/\/www.orioncenter.be\/boogschieten\/","name":"Boogschieten: Het hele jaar door plezier","isPartOf":{"@id":"https:\/\/www.orioncenter.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage"},"image":{"@id":"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg","datePublished":"2025-09-28T16:11:45+00:00","dateModified":"2025-10-18T20:17:04+00:00","description":"Ontdek boogschieten in ons multisportcentrum. Train het hele jaar door binnen op een professionele boogstand van 30 meter.","breadcrumb":{"@id":"https:\/\/www.orioncenter.be\/boogschieten\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.orioncenter.be\/boogschieten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.orioncenter.be\/boogschieten\/#primaryimage","url":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg","contentUrl":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2025\/09\/dreamstime_m_290493574-payed-15-09-25-compressed-1024x770.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.orioncenter.be\/boogschieten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.orioncenter.be\/"},{"@type":"ListItem","position":2,"name":"Boogschieten"}]},{"@type":"WebSite","@id":"https:\/\/www.orioncenter.be\/#website","url":"https:\/\/www.orioncenter.be\/","name":"Orioncenter.be","description":"Belgium's premier shooting range","publisher":{"@id":"https:\/\/www.orioncenter.be\/#organization"},"alternateName":"Orion Training Center","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.orioncenter.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.orioncenter.be\/#organization","name":"Centre de formation Orion","alternateName":"Orion Training Center","url":"https:\/\/www.orioncenter.be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.orioncenter.be\/#\/schema\/logo\/image\/","url":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2024\/11\/Logo-website-2024-transparant-metal.png","contentUrl":"https:\/\/www.orioncenter.be\/wp-content\/uploads\/2024\/11\/Logo-website-2024-transparant-metal.png","width":1875,"height":625,"caption":"Orion Training Center"},"image":{"@id":"https:\/\/www.orioncenter.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61567727466888","https:\/\/www.youtube.com\/channel\/UCSOma6ruzcdrtKz72WYeTVQ","https:\/\/www.instagram.com\/oriontrainingcenter_belgium?igsh=OTdwdHc5M2tuNTl4&utm_source=qr"]}]}},"_links":{"self":[{"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/pages\/8159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/comments?post=8159"}],"version-history":[{"count":94,"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/pages\/8159\/revisions"}],"predecessor-version":[{"id":8670,"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/pages\/8159\/revisions\/8670"}],"wp:attachment":[{"href":"https:\/\/www.orioncenter.be\/fr_be\/wp-json\/wp\/v2\/media?parent=8159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}